{"id":7380,"date":"2025-04-16T17:39:45","date_gmt":"2025-04-16T17:39:45","guid":{"rendered":"https:\/\/insider-gaming.com\/br\/?p=7380"},"modified":"2025-04-16T17:39:47","modified_gmt":"2025-04-16T17:39:47","slug":"phil-spencer-afirma-que-o-xbox-game-pass-nao-e-para-todos","status":"publish","type":"post","link":"https:\/\/insider-gaming.com\/br\/phil-spencer-afirma-que-o-xbox-game-pass-nao-e-para-todos\/","title":{"rendered":"Phil Spencer afirma que o Xbox Game Pass n\u00e3o \u00e9 para todos"},"content":{"rendered":"\n<p>O Xbox Game Pass j\u00e1 est\u00e1 consolidado dentro da ind\u00fastria dos jogos, contudo, ele n\u00e3o \u00e9 para todos os tipos de jogadores, segundo Phil Spencer, o CEO da Microsoft Gaming.<\/p>\n\n\n\n<p>Em uma entrevista ao <a href=\"https:\/\/variety.com\/2025\/gaming\/news\/microsoft-phil-spencer-minecraft-movie-fallout-season-2-1236352653\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Variety<\/a>, Spencer comentou sobre o servi\u00e7o de jogos da Microsoft e como ele se encaixa em diferentes p\u00fablicos alvo:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Para mim, eu olho para o Game Pass como uma op\u00e7\u00e3o saud\u00e1vel para certas pessoas. N\u00e3o \u00e9 para todos. Se voc\u00ea joga um ou dois jogos por ano, o Game Pass provavelmente n\u00e3o \u00e9 o modelo de neg\u00f3cio indicado para voc\u00ea. Deve simplesmente comprar esses dois jogos, e isso faz todo o sentido. Mas eu quero que voc\u00ea tenha escolha<\/p>\n<cite>Phil Spencer, CEO da Microsoft Gaming<\/cite><\/blockquote>\n\n\n\n<p>A afirma\u00e7\u00e3o vai no sentido de que n\u00e3o faz sentido manter uma assinatura ativa de forma recorrente, com um cat\u00e1logo rotativo de jogos, se o jogador ir\u00e1 desfrutar de poucos t\u00edtulos. Nesses casos, a melhor op\u00e7\u00e3o \u00e9 adquirir o jogo de forma definitiva.<\/p>\n\n\n\n<p>Por isso, Spencer cita a import\u00e2ncia de disponibilizar os jogos n\u00e3o apenas via assinatura, mas tamb\u00e9m para compra individual, abrangendo todos os perfis de jogadores:<\/p>\n\n\n\n<p>&#8220;Estamos a disponibilizar esses jogos para compra em mais locais. E eu olho para as horas gerais das pessoas que est\u00e3o jogando no Xbox, jogando nossos jogos, e esse \u00e9 um n\u00famero que continua a crescer de forma bastante substancial. Essa \u00e9 realmente a m\u00e9trica que eu considero para medir o sucesso.&#8221;<\/p>\n\n\n\n<p><strong>Voc\u00ea concorda com a afirma\u00e7\u00e3o do Phil Spencer sobre o Game Pass? <\/strong><\/p>\n\n\n\n<p>Deixe sua opini\u00e3o nos coment\u00e1rios e participe da discuss\u00e3o em nosso&nbsp;<a href=\"https:\/\/insider-gaming.com\/forum\/\" target=\"_blank\" rel=\"noreferrer noopener\">f\u00f3rum<\/a>!<\/p>\n\n\n\n<p>Para not\u00edcias em primeira m\u00e3o, acompanhe nossas redes sociais e ingresse em nosso grupo no WhatsApp.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/x.com\/InsiderGamingBR\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>X (Twitter) \u2013 @InsiderGamingBR<\/strong><\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/chat.whatsapp.com\/C01fPNOHNZzFkCzfR1FUDj\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Grupo da Insider Gaming BR<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Phil Spencer afirma que o Game Pass n\u00e3o \u00e9 um servi\u00e7o para todos os tipos de jogadores.<\/p>\n","protected":false},"author":69,"featured_media":7381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","ig_views":225,"event_dates":"","event_type":"","event_title":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22],"tags":[41],"class_list":["post-7380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-xbox"],"author_data":{"id":69,"name":"Erick Oliveira","avatar":"https:\/\/secure.gravatar.com\/avatar\/5611afc7ce3808a9f4d30ca0610fe040?s=96&d=mm&r=g"},"category":{"primary":{"id":22,"label":"Not\u00edcias","slug":"news"},"others":[]},"thumbnail":{"full":"https:\/\/insider-gaming.com\/br\/wp-content\/uploads\/sites\/2\/2025\/04\/Design-sem-nome-1-17.jpg","large":"https:\/\/insider-gaming.com\/br\/wp-content\/uploads\/sites\/2\/2025\/04\/Design-sem-nome-1-17-1024x576.jpg","medium":"https:\/\/insider-gaming.com\/br\/wp-content\/uploads\/sites\/2\/2025\/04\/Design-sem-nome-1-17-300x169.jpg","medium_large":"https:\/\/insider-gaming.com\/br\/wp-content\/uploads\/sites\/2\/2025\/04\/Design-sem-nome-1-17-770x433.jpg","small":"https:\/\/insider-gaming.com\/br\/wp-content\/uploads\/sites\/2\/2025\/04\/Design-sem-nome-1-17-100x100.jpg"},"app_link":"https:\/\/insider-gaming.com\/br\/app\/post\/phil-spencer-afirma-que-o-xbox-game-pass-nao-e-para-todos","jetpack_featured_media_url":"https:\/\/insider-gaming.com\/br\/wp-content\/uploads\/sites\/2\/2025\/04\/Design-sem-nome-1-17.jpg","jetpack_sharing_enabled":true,"engagement":{"views":225,"likes":0,"comments":0},"_links":{"self":[{"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/posts\/7380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/comments?post=7380"}],"version-history":[{"count":1,"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/posts\/7380\/revisions"}],"predecessor-version":[{"id":7382,"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/posts\/7380\/revisions\/7382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/media\/7381"}],"wp:attachment":[{"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/media?parent=7380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/categories?post=7380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/insider-gaming.com\/br\/wp-json\/wp\/v2\/tags?post=7380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}